{"id":1493,"date":"2019-09-17T11:13:22","date_gmt":"2019-09-17T09:13:22","guid":{"rendered":"http:\/\/impeco.com.pl\/produkt\/sensorgesteuerter-handetrockner\/"},"modified":"2024-02-21T14:31:35","modified_gmt":"2024-02-21T13:31:35","slug":"sensorgesteuerter-handetrockner","status":"publish","type":"product","link":"https:\/\/impeco.com.pl\/de\/produkt\/sensorgesteuerter-handetrockner\/","title":{"rendered":"Sensorgesteuerter H\u00e4ndetrockner Breeze"},"content":{"rendered":"<p><strong>Artikel HD1H14<\/strong><\/p>\n<table>\n<tbody>\n<tr>\n<td>Geh\u00e4use<\/td>\n<td>ABS Kunsstoff, wei\u00df<\/td>\n<\/tr>\n<tr>\n<td>Ein\/Aus<\/td>\n<td>Automatisch, sensorgesteuert<\/td>\n<\/tr>\n<tr>\n<td>Leistung<\/td>\n<td>2000 W<\/td>\n<\/tr>\n<tr>\n<td>Spannung<\/td>\n<td>220-240 V (50\/60 Hz)<\/td>\n<\/tr>\n<tr>\n<td>Luftleistung<\/td>\n<td>80 m3\/h<\/td>\n<\/tr>\n<tr>\n<td>Luftgeschwindigkeit<\/td>\n<td>13 m\/s<\/td>\n<\/tr>\n<tr>\n<td>Lautst\u00e4rke<\/td>\n<td>60 dB<\/td>\n<\/tr>\n<tr>\n<td>Trocknungszeit<\/td>\n<td>35 s<\/td>\n<\/tr>\n<tr>\n<td>Schutzklasse<\/td>\n<td>IPx1<\/td>\n<\/tr>\n<tr>\n<td>Lufttemperatur<\/td>\n<td>42\u2103 (bei Umgebungstemperatur 25\u2103)<\/td>\n<\/tr>\n<tr>\n<td>Gewicht<\/td>\n<td>2,25 kg<\/td>\n<\/tr>\n<tr>\n<td>Ma\u00dfe<\/td>\n<td>H: 250 mm, B: 240 mm, T: 230 mm<\/td>\n<\/tr>\n<tr>\n<td>Garantie<\/td>\n<td>12 Monate<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Der H\u00e4ndetrockner Breeze ist das Basismodell im Angebot von Impeco &#8211; ein hygienisches, kratzfestes ABS. Entwickelt f\u00fcr wenig frequentierte Bereiche wie kleine B\u00fcros und Restaurants. Kompakter Trockner, ideal f\u00fcr Orte mit wenig Freiraum. Ausgestattet mit einem 2000 W B\u00fcrstenmotor und Heizung.<\/p>\n","protected":false},"featured_media":1748,"template":"","meta":[],"product_brand":[],"product_cat":[66,84],"product_tag":[],"class_list":{"0":"post-1493","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-haendetrockner","7":"product_cat-haendetrockner-abs-kunststoff","8":"description-off","10":"first","11":"instock","12":"shipping-taxable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sensorgesteuerter H\u00e4ndetrockner Breeze | Impeco Wroc\u0142aw<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/impeco.com.pl\/de\/produkt\/sensorgesteuerter-handetrockner\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sensorgesteuerter H\u00e4ndetrockner Breeze | Impeco Wroc\u0142aw\" \/>\n<meta property=\"og:description\" content=\"Der H\u00e4ndetrockner Breeze ist das Basismodell im Angebot von Impeco - ein hygienisches, kratzfestes ABS. Entwickelt f\u00fcr wenig frequentierte Bereiche wie kleine B\u00fcros und Restaurants. Kompakter Trockner, ideal f\u00fcr Orte mit wenig Freiraum. Ausgestattet mit einem 2000 W B\u00fcrstenmotor und Heizung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/impeco.com.pl\/de\/produkt\/sensorgesteuerter-handetrockner\/\" \/>\n<meta property=\"og:site_name\" content=\"Impeco Wroc\u0142aw\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-21T13:31:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/impeco.com.pl\/wp-content\/uploads\/2019\/09\/HD1H14-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/impeco.com.pl\/de\/produkt\/sensorgesteuerter-handetrockner\/\",\"url\":\"https:\/\/impeco.com.pl\/de\/produkt\/sensorgesteuerter-handetrockner\/\",\"name\":\"Sensorgesteuerter H\u00e4ndetrockner Breeze | Impeco Wroc\u0142aw\",\"isPartOf\":{\"@id\":\"https:\/\/impeco.com.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/impeco.com.pl\/de\/produkt\/sensorgesteuerter-handetrockner\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/impeco.com.pl\/de\/produkt\/sensorgesteuerter-handetrockner\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/impeco.com.pl\/wp-content\/uploads\/2019\/09\/HD1H14-1-1.jpg\",\"datePublished\":\"2019-09-17T09:13:22+00:00\",\"dateModified\":\"2024-02-21T13:31:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/impeco.com.pl\/de\/produkt\/sensorgesteuerter-handetrockner\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/impeco.com.pl\/de\/produkt\/sensorgesteuerter-handetrockner\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/impeco.com.pl\/de\/produkt\/sensorgesteuerter-handetrockner\/#primaryimage\",\"url\":\"https:\/\/impeco.com.pl\/wp-content\/uploads\/2019\/09\/HD1H14-1-1.jpg\",\"contentUrl\":\"https:\/\/impeco.com.pl\/wp-content\/uploads\/2019\/09\/HD1H14-1-1.jpg\",\"width\":1500,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/impeco.com.pl\/de\/produkt\/sensorgesteuerter-handetrockner\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/impeco.com.pl\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sortiment\",\"item\":\"https:\/\/impeco.com.pl\/de\/sortiment\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sensorgesteuerter H\u00e4ndetrockner Breeze\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/impeco.com.pl\/#website\",\"url\":\"https:\/\/impeco.com.pl\/\",\"name\":\"Impeco Wroc\u0142aw\",\"description\":\"Oferujemy szeroki asortyment wyposa\u017cenia toalet publicznych\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/impeco.com.pl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sensorgesteuerter H\u00e4ndetrockner Breeze | Impeco Wroc\u0142aw","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/impeco.com.pl\/de\/produkt\/sensorgesteuerter-handetrockner\/","og_locale":"de_DE","og_type":"article","og_title":"Sensorgesteuerter H\u00e4ndetrockner Breeze | Impeco Wroc\u0142aw","og_description":"Der H\u00e4ndetrockner Breeze ist das Basismodell im Angebot von Impeco - ein hygienisches, kratzfestes ABS. Entwickelt f\u00fcr wenig frequentierte Bereiche wie kleine B\u00fcros und Restaurants. Kompakter Trockner, ideal f\u00fcr Orte mit wenig Freiraum. Ausgestattet mit einem 2000 W B\u00fcrstenmotor und Heizung.","og_url":"https:\/\/impeco.com.pl\/de\/produkt\/sensorgesteuerter-handetrockner\/","og_site_name":"Impeco Wroc\u0142aw","article_modified_time":"2024-02-21T13:31:35+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/impeco.com.pl\/wp-content\/uploads\/2019\/09\/HD1H14-1-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/impeco.com.pl\/de\/produkt\/sensorgesteuerter-handetrockner\/","url":"https:\/\/impeco.com.pl\/de\/produkt\/sensorgesteuerter-handetrockner\/","name":"Sensorgesteuerter H\u00e4ndetrockner Breeze | Impeco Wroc\u0142aw","isPartOf":{"@id":"https:\/\/impeco.com.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/impeco.com.pl\/de\/produkt\/sensorgesteuerter-handetrockner\/#primaryimage"},"image":{"@id":"https:\/\/impeco.com.pl\/de\/produkt\/sensorgesteuerter-handetrockner\/#primaryimage"},"thumbnailUrl":"https:\/\/impeco.com.pl\/wp-content\/uploads\/2019\/09\/HD1H14-1-1.jpg","datePublished":"2019-09-17T09:13:22+00:00","dateModified":"2024-02-21T13:31:35+00:00","breadcrumb":{"@id":"https:\/\/impeco.com.pl\/de\/produkt\/sensorgesteuerter-handetrockner\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/impeco.com.pl\/de\/produkt\/sensorgesteuerter-handetrockner\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/impeco.com.pl\/de\/produkt\/sensorgesteuerter-handetrockner\/#primaryimage","url":"https:\/\/impeco.com.pl\/wp-content\/uploads\/2019\/09\/HD1H14-1-1.jpg","contentUrl":"https:\/\/impeco.com.pl\/wp-content\/uploads\/2019\/09\/HD1H14-1-1.jpg","width":1500,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/impeco.com.pl\/de\/produkt\/sensorgesteuerter-handetrockner\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/impeco.com.pl\/de\/"},{"@type":"ListItem","position":2,"name":"Sortiment","item":"https:\/\/impeco.com.pl\/de\/sortiment\/"},{"@type":"ListItem","position":3,"name":"Sensorgesteuerter H\u00e4ndetrockner Breeze"}]},{"@type":"WebSite","@id":"https:\/\/impeco.com.pl\/#website","url":"https:\/\/impeco.com.pl\/","name":"Impeco Wroc\u0142aw","description":"Oferujemy szeroki asortyment wyposa\u017cenia toalet publicznych","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/impeco.com.pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/impeco.com.pl\/de\/wp-json\/wp\/v2\/product\/1493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/impeco.com.pl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/impeco.com.pl\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/impeco.com.pl\/de\/wp-json\/wp\/v2\/media\/1748"}],"wp:attachment":[{"href":"https:\/\/impeco.com.pl\/de\/wp-json\/wp\/v2\/media?parent=1493"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/impeco.com.pl\/de\/wp-json\/wp\/v2\/product_brand?post=1493"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/impeco.com.pl\/de\/wp-json\/wp\/v2\/product_cat?post=1493"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/impeco.com.pl\/de\/wp-json\/wp\/v2\/product_tag?post=1493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}